

{"id":2143,"date":"2023-09-04T14:47:15","date_gmt":"2023-09-04T13:47:15","guid":{"rendered":"https:\/\/bs.xl.pt\/premio-nacional-agricultura\/?post_type=attendants&#038;p=2143"},"modified":"2024-09-03T12:19:47","modified_gmt":"2024-09-03T11:19:47","slug":"alvaro-mendonca-e-moura","status":"publish","type":"attendants","link":"https:\/\/bs.xl.pt\/premio-nacional-agricultura\/attendants\/alvaro-mendonca-e-moura\/","title":{"rendered":"\u00c1lvaro Mendon\u00e7a e Moura"},"content":{"rendered":"\n<p>Origin\u00e1rio de uma fam\u00edlia com fortes ra\u00edzes transmontanas e ligado desde sempre por tradi\u00e7\u00e3o familiar \u00e0 agricultura em Tr\u00e1s-os-Montes, onde passou uma parte da sua juventude, foi educado a ouvir as ideias do Eng. Camilo de Mendon\u00e7a sobre o desenvolvimento da agricultura em Portugal e em particular em Tr\u00e1s-os-Montes, assistindo desde o in\u00edcio \u00e0 cria\u00e7\u00e3o e crescimento do Complexo agroindustrial do Cach\u00e3o. Tendo assumido a condu\u00e7\u00e3o dos neg\u00f3cios agr\u00edcolas da fam\u00edlia procedeu a uma profunda reconvers\u00e3o dos mesmos tendo criado uma Sociedade familiar de que \u00e9 o principal s\u00f3cio. Dedica-se especialmente ao olival, vinha e amendoal e obteve um pr\u00e9mio internacional de azeite em Israel. \u00c9 nomeadamente s\u00f3cio da APPITAD \u2013 Associa\u00e7\u00e3o dos produtores em prote\u00e7\u00e3o integrada de Tr\u00e1s-os-Montes e Alto Douro e da AM\u00caNDOACOOP \u2013 Cooperativa dos produtores de am\u00eandoa de Torre de Moncorvo. Foi professor universit\u00e1rio e \u00e9 membro fundador do C\u00edrculo de Estudos do Centralismo.<\/p>\n\n\n\n<p>\u00c9 Licenciado em Direito pela Universidade de Coimbra e assume a presid\u00eancia da CAP &#8211; Confedera\u00e7\u00e3o dos Agricultores de Portugal, desde maio de 2023.<\/p>\n","protected":false},"featured_media":2197,"template":"","meta":[],"categories":[],"tags":[],"attendant_categories":[],"class_list":["post-2143","attendants","type-attendants","status-publish","has-post-thumbnail","hentry"],"_links":{"self":[{"href":"https:\/\/bs.xl.pt\/premio-nacional-agricultura\/wp-json\/wp\/v2\/attendants\/2143","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bs.xl.pt\/premio-nacional-agricultura\/wp-json\/wp\/v2\/attendants"}],"about":[{"href":"https:\/\/bs.xl.pt\/premio-nacional-agricultura\/wp-json\/wp\/v2\/types\/attendants"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bs.xl.pt\/premio-nacional-agricultura\/wp-json\/wp\/v2\/media\/2197"}],"wp:attachment":[{"href":"https:\/\/bs.xl.pt\/premio-nacional-agricultura\/wp-json\/wp\/v2\/media?parent=2143"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/bs.xl.pt\/premio-nacional-agricultura\/wp-json\/wp\/v2\/categories?post=2143"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/bs.xl.pt\/premio-nacional-agricultura\/wp-json\/wp\/v2\/tags?post=2143"},{"taxonomy":"attendant_categories","embeddable":true,"href":"https:\/\/bs.xl.pt\/premio-nacional-agricultura\/wp-json\/wp\/v2\/attendant_categories?post=2143"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}