{"id":1418,"date":"2021-09-27T21:32:34","date_gmt":"2021-09-27T21:32:34","guid":{"rendered":"http:\/\/bs.xl.pt\/sustentabilidade-2030\/?post_type=attendants&#038;p=1418"},"modified":"2025-02-26T09:20:44","modified_gmt":"2025-02-26T09:20:44","slug":"alexandre-scarlet","status":"publish","type":"attendants","link":"https:\/\/bs.xl.pt\/sustentabilidade-2030\/attendants\/alexandre-scarlet\/","title":{"rendered":"Alexandre Scarlet"},"content":{"rendered":"\n<p>Licenciado em Gest\u00e3o, Alexandre Scarlet iniciou a sua carreira profissional na Allianz<br>Portugal como Analista S\u00e9nior, em 2001.<br>Em 2010 assumiu na Heliportugal a posi\u00e7\u00e3o de Diretor de Planeamento e Controlo,<br>tendo em 2012 assumido este mesmo cargo, mas na seguradora Generali, onde 3<br>anos depois viria a ocupar a lideran\u00e7a da Dire\u00e7\u00e3o Financeira, como CFO e membro<br>do Comit\u00e9 Executivo.<br>Em 2020 Alexandre regressa \u00e0s origens, como CFO da Allianz Portugal e membro do<br>Comit\u00e9 Executivo, cargo que mant\u00e9m at\u00e9 \u00e0 data.<\/p>\n","protected":false},"featured_media":1421,"template":"","meta":[],"categories":[127],"tags":[343],"attendant_categories":[],"class_list":["post-1418","attendants","type-attendants","status-publish","has-post-thumbnail","hentry","category-governacao","tag-edicao-2024-25"],"_links":{"self":[{"href":"https:\/\/bs.xl.pt\/sustentabilidade-2030\/wp-json\/wp\/v2\/attendants\/1418","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bs.xl.pt\/sustentabilidade-2030\/wp-json\/wp\/v2\/attendants"}],"about":[{"href":"https:\/\/bs.xl.pt\/sustentabilidade-2030\/wp-json\/wp\/v2\/types\/attendants"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bs.xl.pt\/sustentabilidade-2030\/wp-json\/wp\/v2\/media\/1421"}],"wp:attachment":[{"href":"https:\/\/bs.xl.pt\/sustentabilidade-2030\/wp-json\/wp\/v2\/media?parent=1418"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/bs.xl.pt\/sustentabilidade-2030\/wp-json\/wp\/v2\/categories?post=1418"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/bs.xl.pt\/sustentabilidade-2030\/wp-json\/wp\/v2\/tags?post=1418"},{"taxonomy":"attendant_categories","embeddable":true,"href":"https:\/\/bs.xl.pt\/sustentabilidade-2030\/wp-json\/wp\/v2\/attendant_categories?post=1418"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}